{"id":1211,"count":1,"description":"","link":"https:\/\/bucharesttrend.eu\/uk\/tag\/avangard","name":"\u0430\u0432\u0430\u043d\u0433\u0430\u0440\u0434","slug":"avangard","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/bucharesttrend.eu\/uk\/wp-json\/wp\/v2\/tags\/1211","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bucharesttrend.eu\/uk\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/bucharesttrend.eu\/uk\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/bucharesttrend.eu\/uk\/wp-json\/wp\/v2\/posts?tags=1211"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}