{"id":1207,"count":1,"description":"","link":"https:\/\/bucharesttrend.eu\/uk\/tag\/poet-jon-minulesku","name":"\u043f\u043e\u0435\u0442 \u0419\u043e\u043d \u041c\u0456\u043d\u0443\u043b\u0435\u0441\u043a\u0443","slug":"poet-jon-minulesku","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/bucharesttrend.eu\/uk\/wp-json\/wp\/v2\/tags\/1207","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bucharesttrend.eu\/uk\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/bucharesttrend.eu\/uk\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/bucharesttrend.eu\/uk\/wp-json\/wp\/v2\/posts?tags=1207"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}